{"id":34303,"date":"2024-07-30T18:00:00","date_gmt":"2024-07-30T16:00:00","guid":{"rendered":"https:\/\/rechtsanwalt.fr\/?p=34303"},"modified":"2025-03-12T10:09:53","modified_gmt":"2025-03-12T09:09:53","slug":"le-report-des-pertes-en-allemagne","status":"publish","type":"post","link":"https:\/\/rechtsanwalt.fr\/fr\/le-report-des-pertes-en-allemagne\/","title":{"rendered":"Le report des pertes en Allemagne"},"content":{"rendered":"\n<p>31 juillet 2024<\/p>\n\n\n<div class=\"boimg-circle-rechtsgebiete-team-kontakt boimg-left-space\">\n<div class=\"boimg-circle_img1\"><a href=\"https:\/\/rechtsanwalt.fr\/fr\/equipe\/audrey-bourquin\/\"><img decoding=\"async\" src=\"https:\/\/rechtsanwalt.fr\/wp-content\/uploads\/2024\/01\/portrait_audrey_bourquin_epp.jpg\"><\/a><\/div>\n<div class=\"botext-circle\"><a href=\"https:\/\/rechtsanwalt.fr\/fr\/equipe\/audrey-bourquin\/\">Audrey Bourquin <sup>DJCE<\/sup><\/a><\/div>\n<div class=\"botext-circle-sub\">Rechtsanw\u00e4ltin\/Avocat<\/div>\n<div class=\"botext-circle-sub\"><a onclick=\"return gtag_report_conversion('mailto:bourquin@rechtsanwalt.fr');\" href=\"mailto:bourquin@rechtsanwalt.fr\">bourquin@rechtsanwalt.fr<\/a><\/div>\n<div class=\"botext-circle-sub-tel\"><a href=\"tel:00497221302370\">+49 (0) 7221 30 23 70<\/a><\/div>\n<\/div>\n<div style=\"height:40px\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p>Les pertes r\u00e9alis\u00e9es par une soci\u00e9t\u00e9 allemande au cours d\u2019un exercice peuvent \u00eatre imput\u00e9es sur le r\u00e9sultat des exercices suivants ou au cours de l\u2019exercice pr\u00e9c\u00e9dent et ainsi diminuer l\u2019imp\u00f4t d\u00fb au cours des exercices b\u00e9n\u00e9ficiaires.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Report en avant des pertes<\/h2>\n\n\n\n<p>Le report en avant (<em>carry forward<\/em>) des pertes en Allemagne est <strong>limit\u00e9 \u00e0 1 million d\u2019euros augment\u00e9 de 70%<\/strong> (pour les exercices \u00e0 compter de 2024 jusque 2027) des pertes d\u00e9passant 1 million d\u2019euros.<\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter size-full is-resized\"><img decoding=\"async\" width=\"1280\" height=\"280\" src=\"https:\/\/rechtsanwalt.fr\/wp-content\/uploads\/2024\/08\/09_AB_publication_Le-report-des-pertes-en-Allemagne_1.jpg\" alt=\"\" class=\"wp-image-34377\" style=\"width:650px\" srcset=\"https:\/\/rechtsanwalt.fr\/wp-content\/uploads\/2024\/08\/09_AB_publication_Le-report-des-pertes-en-Allemagne_1.jpg 1280w, https:\/\/rechtsanwalt.fr\/wp-content\/uploads\/2024\/08\/09_AB_publication_Le-report-des-pertes-en-Allemagne_1-300x66.jpg 300w, https:\/\/rechtsanwalt.fr\/wp-content\/uploads\/2024\/08\/09_AB_publication_Le-report-des-pertes-en-Allemagne_1-1030x225.jpg 1030w, https:\/\/rechtsanwalt.fr\/wp-content\/uploads\/2024\/08\/09_AB_publication_Le-report-des-pertes-en-Allemagne_1-768x168.jpg 768w, https:\/\/rechtsanwalt.fr\/wp-content\/uploads\/2024\/08\/09_AB_publication_Le-report-des-pertes-en-Allemagne_1-705x154.jpg 705w\" sizes=\"(max-width: 1280px) 100vw, 1280px\" \/><\/figure>\n\n\n\n<p>Exemple : La soci\u00e9t\u00e9 allemande r\u00e9alise un b\u00e9n\u00e9fice de 1.250.000 \u20ac. Elle dispose d\u2019une r\u00e9serve de perte de 2.000.000 \u20ac.<\/p>\n\n\n\n<p>Perte admise en d\u00e9duction : 1.000.000\u20ac + 70% x (1.250.000- 1.000.000) = 1.175.000<\/p>\n\n\n\n<p>B\u00e9n\u00e9fice imposable restant : 75.000\u20ac<\/p>\n\n\n\n<p><\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Report en arri\u00e8re des pertes<\/h2>\n\n\n\n<p>Le report en arri\u00e8re (<em>carry back<\/em>) des pertes en Allemagne est <strong>limit\u00e9 \u00e0 1 million d\u2019euros<\/strong> et ne peut porter <strong>que sur l\u2019ann\u00e9e pr\u00e9c\u00e9dant la r\u00e9alisation des pertes<\/strong>. Le report en arri\u00e8re est en principe effectu\u00e9 d\u2019office par l\u2019administration fiscale allemande. Il est possible toutefois de renoncer \u00e0 son application.<\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter size-full is-resized\"><img decoding=\"async\" width=\"1280\" height=\"280\" src=\"https:\/\/rechtsanwalt.fr\/wp-content\/uploads\/2024\/08\/09_AB_publication_Le-report-des-pertes-en-Allemagne_2.jpg\" alt=\"\" class=\"wp-image-34380\" style=\"width:650px\" srcset=\"https:\/\/rechtsanwalt.fr\/wp-content\/uploads\/2024\/08\/09_AB_publication_Le-report-des-pertes-en-Allemagne_2.jpg 1280w, https:\/\/rechtsanwalt.fr\/wp-content\/uploads\/2024\/08\/09_AB_publication_Le-report-des-pertes-en-Allemagne_2-300x66.jpg 300w, https:\/\/rechtsanwalt.fr\/wp-content\/uploads\/2024\/08\/09_AB_publication_Le-report-des-pertes-en-Allemagne_2-1030x225.jpg 1030w, https:\/\/rechtsanwalt.fr\/wp-content\/uploads\/2024\/08\/09_AB_publication_Le-report-des-pertes-en-Allemagne_2-768x168.jpg 768w, https:\/\/rechtsanwalt.fr\/wp-content\/uploads\/2024\/08\/09_AB_publication_Le-report-des-pertes-en-Allemagne_2-705x154.jpg 705w\" sizes=\"(max-width: 1280px) 100vw, 1280px\" \/><\/figure>\n\n\n\n<p><\/p>\n\n\n\n<div style=\"height:22px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div style=\"height:10px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\nNous sommes \u00e0 votre disposition pour toute question relative au report des pertes en Allemagne.<br><a style=\"font-family: Calibri Bold,Open Sans Bold; color: #023f7c;\" href=\"mailto:welcome@rechtsanwalt.fr\">welcome@rechtsanwalt.fr<\/a>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<iframe loading=\"lazy\" src=\"https:\/\/rechtsanwalt.fr\/wp-content\/uploads\/2024\/08\/AB_publication_Le-report-des-pertes-en-Allemagne.pdf\" id=\"printFrame\" width=\"0\" height=\"0\" frameborder=\"0\"><\/iframe>\n<a href=\"https:\/\/rechtsanwalt.fr\/wp-content\/uploads\/2024\/08\/AB_publication_Le-report-des-pertes-en-Allemagne.pdf\" target=\"_blank\" class=\"print-link\" rel=\"noopener noreferrer\">Ouvrir PDF<\/a>\n<a class=\"print-link\" onclick=\"print()\">Imprimer<\/a>\n\n\n\n<div style=\"height:5px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div style=\"height:40px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<br>\n<a href=\"https:\/\/expertisecomptable.de\" target=\"_blank\" rel=\"noopener noreferrer nofollow\"><img decoding=\"async\" style=\"padding-left: 0px; vertical-align: text-top;\" src=\"https:\/\/rechtsanwalt.fr\/wp-content\/uploads\/2024\/03\/logo_web_epp_tax_posts.png\" alt=\"EPP TAX\" width=\"170\" height=\"25\"><\/a>\n<br>\nAvec le d\u00e9veloppement de notre branche d\u2019activit\u00e9 EPP TAX, nous accompagnons les soci\u00e9t\u00e9s fran\u00e7aises, belges et suisses et leurs filiales en Allemagne dans toutes les probl\u00e9matiques fiscales, comptables et de gestion des ressources humaines rencontr\u00e9es outre-Rhin.<br>\n<a style=\"font-family: Calibri Bold,Open Sans Bold; color: #0c795e;\" href=\"mailto:welcome@expertisecomptable.de\">welcome@expertisecomptable.de<\/a>\n<br>\n\n\n\n<div style=\"height:100px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n","protected":false},"excerpt":{"rendered":"<p>31 juillet 2024 Les pertes r\u00e9alis\u00e9es par une soci\u00e9t\u00e9 allemande au cours d\u2019un exercice peuvent \u00eatre imput\u00e9es sur le r\u00e9sultat des exercices suivants ou au cours de l\u2019exercice pr\u00e9c\u00e9dent et ainsi diminuer l\u2019imp\u00f4t d\u00fb au cours des exercices b\u00e9n\u00e9ficiaires. Report en avant des pertes Le report en avant (carry forward) des pertes en Allemagne est [&hellip;]<\/p>\n","protected":false},"author":16,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"footnotes":""},"categories":[252],"tags":[],"class_list":["post-34303","post","type-post","status-publish","format-standard","hentry","category-fiscalite-des-entreprises"],"_links":{"self":[{"href":"https:\/\/rechtsanwalt.fr\/fr\/wp-json\/wp\/v2\/posts\/34303","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/rechtsanwalt.fr\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/rechtsanwalt.fr\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/rechtsanwalt.fr\/fr\/wp-json\/wp\/v2\/users\/16"}],"replies":[{"embeddable":true,"href":"https:\/\/rechtsanwalt.fr\/fr\/wp-json\/wp\/v2\/comments?post=34303"}],"version-history":[{"count":0,"href":"https:\/\/rechtsanwalt.fr\/fr\/wp-json\/wp\/v2\/posts\/34303\/revisions"}],"wp:attachment":[{"href":"https:\/\/rechtsanwalt.fr\/fr\/wp-json\/wp\/v2\/media?parent=34303"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/rechtsanwalt.fr\/fr\/wp-json\/wp\/v2\/categories?post=34303"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/rechtsanwalt.fr\/fr\/wp-json\/wp\/v2\/tags?post=34303"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}